{"id":23378,"date":"2025-08-14T15:16:11","date_gmt":"2025-08-14T12:16:11","guid":{"rendered":"https:\/\/vertigo.org.il\/wp-content\/uploads\/2025\/08\/rehem2.jpg"},"modified":"2025-08-14T15:16:11","modified_gmt":"2025-08-14T12:16:11","slug":"rehem2-2","status":"inherit","type":"attachment","link":"https:\/\/vertigo.org.il\/en\/rehem2-2\/","title":{"rendered":"rehem2"},"author":20,"featured_media":0,"comment_status":"","ping_status":"closed","template":"","meta":[],"class_list":["post-23378","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>rehem2 - Vertigo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vertigo.org.il\/wp-content\/uploads\/2025\/08\/rehem2.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"rehem2 - Vertigo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vertigo.org.il\/wp-content\/uploads\/2025\/08\/rehem2.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Vertigo\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vertigo.org.il\/wp-content\/uploads\/2025\/08\/rehem2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1514\" \/>\n\t<meta property=\"og:image:height\" content=\"855\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vertigo.org.il\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/rehem2.jpg\",\"url\":\"https:\\\/\\\/vertigo.org.il\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/rehem2.jpg\",\"name\":\"rehem2 - Vertigo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vertigo.org.il\\\/#website\"},\"datePublished\":\"2025-08-14T12:16:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vertigo.org.il\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/rehem2.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vertigo.org.il\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/rehem2.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vertigo.org.il\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/rehem2.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea\",\"item\":\"https:\\\/\\\/vertigo.org.il\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"rehem2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vertigo.org.il\\\/#website\",\"url\":\"https:\\\/\\\/vertigo.org.il\\\/\",\"name\":\"Vertigo\",\"description\":\"\u05dc\u05d4\u05e7\u05ea \u05d4\u05de\u05d7\u05d5\u05dc \u05d5\u05e8\u05d8\u05d9\u05d2\u05d5\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vertigo.org.il\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"rehem2 - Vertigo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vertigo.org.il\/wp-content\/uploads\/2025\/08\/rehem2.jpg","og_locale":"en_US","og_type":"article","og_title":"rehem2 - Vertigo","og_url":"https:\/\/vertigo.org.il\/wp-content\/uploads\/2025\/08\/rehem2.jpg","og_site_name":"Vertigo","og_image":[{"width":1514,"height":855,"url":"https:\/\/vertigo.org.il\/wp-content\/uploads\/2025\/08\/rehem2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/vertigo.org.il\/wp-content\/uploads\/2025\/08\/rehem2.jpg","url":"https:\/\/vertigo.org.il\/wp-content\/uploads\/2025\/08\/rehem2.jpg","name":"rehem2 - Vertigo","isPartOf":{"@id":"https:\/\/vertigo.org.il\/#website"},"datePublished":"2025-08-14T12:16:11+00:00","breadcrumb":{"@id":"https:\/\/vertigo.org.il\/wp-content\/uploads\/2025\/08\/rehem2.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vertigo.org.il\/wp-content\/uploads\/2025\/08\/rehem2.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/vertigo.org.il\/wp-content\/uploads\/2025\/08\/rehem2.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea","item":"https:\/\/vertigo.org.il\/en\/"},{"@type":"ListItem","position":2,"name":"rehem2"}]},{"@type":"WebSite","@id":"https:\/\/vertigo.org.il\/#website","url":"https:\/\/vertigo.org.il\/","name":"Vertigo","description":"\u05dc\u05d4\u05e7\u05ea \u05d4\u05de\u05d7\u05d5\u05dc \u05d5\u05e8\u05d8\u05d9\u05d2\u05d5","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vertigo.org.il\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/vertigo.org.il\/wp-content\/uploads\/2025\/08\/rehem2.jpg'><img decoding=\"async\" width=\"145\" height=\"82\" src=\"https:\/\/vertigo.org.il\/wp-content\/uploads\/2025\/08\/rehem2-145x82.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/vertigo.org.il\/wp-content\/uploads\/2025\/08\/rehem2-145x82.jpg 145w, https:\/\/vertigo.org.il\/wp-content\/uploads\/2025\/08\/rehem2-1024x578.jpg 1024w, https:\/\/vertigo.org.il\/wp-content\/uploads\/2025\/08\/rehem2-500x282.jpg 500w, https:\/\/vertigo.org.il\/wp-content\/uploads\/2025\/08\/rehem2.jpg 1514w\" sizes=\"(max-width: 145px) 100vw, 145px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1514,"height":855,"file":"2025\/08\/rehem2.jpg","filesize":966447,"sizes":{"medium":{"file":"rehem2-145x82.jpg","width":145,"height":82,"filesize":4747,"mime_type":"image\/jpeg","source_url":"https:\/\/vertigo.org.il\/wp-content\/uploads\/2025\/08\/rehem2-145x82.jpg"},"large":{"file":"rehem2-1024x578.jpg","width":1024,"height":578,"filesize":116513,"mime_type":"image\/jpeg","source_url":"https:\/\/vertigo.org.il\/wp-content\/uploads\/2025\/08\/rehem2-1024x578.jpg"},"thumbnail":{"file":"rehem2-150x150.jpg","width":150,"height":150,"filesize":7539,"mime_type":"image\/jpeg","source_url":"https:\/\/vertigo.org.il\/wp-content\/uploads\/2025\/08\/rehem2-150x150.jpg"},"post-thumbnail":{"file":"rehem2-500x282.jpg","width":500,"height":282,"filesize":35435,"mime_type":"image\/jpeg","source_url":"https:\/\/vertigo.org.il\/wp-content\/uploads\/2025\/08\/rehem2-500x282.jpg"},"gb-post-thumbnail":{"file":"rehem2-500x220.jpg","width":500,"height":220,"filesize":27484,"mime_type":"image\/jpeg","source_url":"https:\/\/vertigo.org.il\/wp-content\/uploads\/2025\/08\/rehem2-500x220.jpg"},"homepage-thumb-a":{"file":"rehem2-909x683.jpg","width":909,"height":683,"filesize":117694,"mime_type":"image\/jpeg","source_url":"https:\/\/vertigo.org.il\/wp-content\/uploads\/2025\/08\/rehem2-909x683.jpg"},"homepage-thumb-b":{"file":"rehem2-466x683.jpg","width":466,"height":683,"filesize":62461,"mime_type":"image\/jpeg","source_url":"https:\/\/vertigo.org.il\/wp-content\/uploads\/2025\/08\/rehem2-466x683.jpg"},"homepage-thumb-c":{"file":"rehem2-1375x305.jpg","width":1375,"height":305,"filesize":64772,"mime_type":"image\/jpeg","source_url":"https:\/\/vertigo.org.il\/wp-content\/uploads\/2025\/08\/rehem2-1375x305.jpg"},"homepage-thumb-d":{"file":"rehem2-448x566.jpg","width":448,"height":566,"filesize":53181,"mime_type":"image\/jpeg","source_url":"https:\/\/vertigo.org.il\/wp-content\/uploads\/2025\/08\/rehem2-448x566.jpg"},"homepage-thumb-e":{"file":"rehem2-448x422.jpg","width":448,"height":422,"filesize":43856,"mime_type":"image\/jpeg","source_url":"https:\/\/vertigo.org.il\/wp-content\/uploads\/2025\/08\/rehem2-448x422.jpg"},"full":{"file":"rehem2.jpg","width":1514,"height":855,"mime_type":"image\/jpeg","source_url":"https:\/\/vertigo.org.il\/wp-content\/uploads\/2025\/08\/rehem2.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":null,"source_url":"https:\/\/vertigo.org.il\/wp-content\/uploads\/2025\/08\/rehem2.jpg","_links":{"self":[{"href":"https:\/\/vertigo.org.il\/en\/wp-json\/wp\/v2\/media\/23378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vertigo.org.il\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/vertigo.org.il\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/vertigo.org.il\/en\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/vertigo.org.il\/en\/wp-json\/wp\/v2\/comments?post=23378"}]}}